{"id":2179,"count":1,"description":"","link":"https:\/\/zackmwekassa.org\/en\/tag\/fundamental-rights\/","name":"fundamental rights","slug":"fundamental-rights","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>fundamental rights - Zack Mwekassa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zackmwekassa.org\/en\/tag\/fundamental-rights\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"fundamental rights\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zackmwekassa.org\/en\/tag\/fundamental-rights\/\" \/>\n<meta property=\"og:site_name\" content=\"Zack Mwekassa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/zackmwekassa.org\\\/en\\\/tag\\\/fundamental-rights\\\/\",\"url\":\"https:\\\/\\\/zackmwekassa.org\\\/en\\\/tag\\\/fundamental-rights\\\/\",\"name\":\"fundamental rights - Zack Mwekassa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zackmwekassa.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zackmwekassa.org\\\/en\\\/tag\\\/fundamental-rights\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zackmwekassa.org\\\/en\\\/tag\\\/fundamental-rights\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/zackmwekassa.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"fundamental rights\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zackmwekassa.org\\\/#website\",\"url\":\"https:\\\/\\\/zackmwekassa.org\\\/\",\"name\":\"Zack Mwekassa\",\"description\":\"Le guerrier noir, votre fr\u00e8re !\",\"publisher\":{\"@id\":\"https:\\\/\\\/zackmwekassa.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zackmwekassa.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/zackmwekassa.org\\\/#organization\",\"name\":\"Zack Mwekassa\",\"url\":\"https:\\\/\\\/zackmwekassa.org\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/zackmwekassa.org\\\/en\\\/tag\\\/fundamental-rights\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/zackmwekassa.org\\\/en\\\/tag\\\/fundamental-rights\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zackmwekassa.org\\\/en\\\/tag\\\/fundamental-rights\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/zackmwekassa.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/cropped-zack-mwekassa-icon.png\",\"contentUrl\":\"https:\\\/\\\/zackmwekassa.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/cropped-zack-mwekassa-icon.png\",\"width\":1920,\"height\":652,\"caption\":\"Zack Mwekassa\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"fundamental rights - Zack Mwekassa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zackmwekassa.org\/en\/tag\/fundamental-rights\/","og_locale":"en_US","og_type":"article","og_title":"fundamental rights","og_url":"https:\/\/zackmwekassa.org\/en\/tag\/fundamental-rights\/","og_site_name":"Zack Mwekassa","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/zackmwekassa.org\/en\/tag\/fundamental-rights\/","url":"https:\/\/zackmwekassa.org\/en\/tag\/fundamental-rights\/","name":"fundamental rights - Zack Mwekassa","isPartOf":{"@id":"https:\/\/zackmwekassa.org\/#website"},"breadcrumb":{"@id":"https:\/\/zackmwekassa.org\/en\/tag\/fundamental-rights\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/zackmwekassa.org\/en\/tag\/fundamental-rights\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/zackmwekassa.org\/en\/"},{"@type":"ListItem","position":2,"name":"fundamental rights"}]},{"@type":"WebSite","@id":"https:\/\/zackmwekassa.org\/#website","url":"https:\/\/zackmwekassa.org\/","name":"Zack Mwekassa","description":"Le guerrier noir, votre fr\u00e8re !","publisher":{"@id":"https:\/\/zackmwekassa.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zackmwekassa.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Organization","Place"],"@id":"https:\/\/zackmwekassa.org\/#organization","name":"Zack Mwekassa","url":"https:\/\/zackmwekassa.org\/","logo":{"@id":"https:\/\/zackmwekassa.org\/en\/tag\/fundamental-rights\/#local-main-organization-logo"},"image":{"@id":"https:\/\/zackmwekassa.org\/en\/tag\/fundamental-rights\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zackmwekassa.org\/en\/tag\/fundamental-rights\/#local-main-organization-logo","url":"https:\/\/zackmwekassa.org\/wp-content\/uploads\/2023\/06\/cropped-zack-mwekassa-icon.png","contentUrl":"https:\/\/zackmwekassa.org\/wp-content\/uploads\/2023\/06\/cropped-zack-mwekassa-icon.png","width":1920,"height":652,"caption":"Zack Mwekassa"}]}},"_links":{"self":[{"href":"https:\/\/zackmwekassa.org\/en\/wp-json\/wp\/v2\/tags\/2179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zackmwekassa.org\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/zackmwekassa.org\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/zackmwekassa.org\/en\/wp-json\/wp\/v2\/posts?tags=2179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}